{"id":27716,"date":"2021-10-14T10:17:18","date_gmt":"2021-10-14T08:17:18","guid":{"rendered":"https:\/\/www.reclamador.es\/blog\/?p=27716"},"modified":"2024-05-29T12:48:26","modified_gmt":"2024-05-29T10:48:26","slug":"fin-al-libor","status":"publish","type":"post","link":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/","title":{"rendered":"Fin al Libor en las hipotecas"},"content":{"rendered":"<div class=\"ttr_start\"><\/div>\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;27716&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;178&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;2.3&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;3&quot;,&quot;greet&quot;:&quot;Valora este art\u00edculo&quot;,&quot;legend&quot;:&quot;2.3\\\/5 - (178 votos)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Fin al Libor en las hipotecas&quot;,&quot;width&quot;:&quot;51.4&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 51.4px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            2.3\/5 - (178 votos)    <\/div>\n    <\/div>\n\n<figure id=\"attachment_27718\" aria-describedby=\"caption-attachment-27718\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27718\" src=\"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg?resize=1200%2C674&#038;ssl=1\" alt=\"libor - reclamador.es\" width=\"1200\" height=\"674\" srcset=\"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg?resize=800%2C449&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg?resize=768%2C431&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-27718\" class=\"wp-caption-text\"><em>\u00bfQu\u00e9 pasar\u00e1 el 1 de enero de 2022 con las hipotecas Libor?<\/em><\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Con el fin del a\u00f1o 2021 tambi\u00e9n llegar\u00e1 el adi\u00f3s al London InterBank Offered Rate -LIBOR- \u00edndice al que estaban referenciadas numerosas hipotecas en nuestro pa\u00eds, principalmente aquellas firmadas con el \u201cboom inmobiliario\u201d y el auge de las conocidas como <strong><a href=\"https:\/\/www.reclamador.es\/banco\/reclamacion-hipoteca-multidivisa\/\">\u201chipotecas multidivisa\u201d<\/a><\/strong>.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para los que no conozcan el Libor, podr\u00eda decirse que es como el Eur\u00edbor pero en este caso para calcularse utiliza como base los tipos de cambios brit\u00e1nicos. Para\u00a0 conocer el dato diario del Libor, el interesado puede entrar en la p\u00e1gina web del Banco de Espa\u00f1a, donde se publica la informaci\u00f3n a diario.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pues bien, pese a que en Espa\u00f1a un gran porcentaje de pr\u00e9stamos hipotecarios est\u00e1 referenciado al Eur\u00edbor, muchos otros, como ya dec\u00edamos, lo est\u00e1n al Libor, que desaparece el pr\u00f3ximo 31 de diciembre de 2021.\u00a0<\/span><\/p>\n<h2><b>\u00bfQu\u00e9 pasar\u00e1 con las hipotecas referenciadas al Libor?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Los hipotecados con pr\u00e9stamos multidivisa est\u00e1n <strong>a la espera de conocer qu\u00e9 alternativa<\/strong> <strong>les ofrece su entidad financiera<\/strong> para continuar con el pago de su hipoteca.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las principales autoridades econ\u00f3mico-bancarias de Europa fijaron como fecha tope el 31 de diciembre de 2021 para dejar de utilizar cualquiera de los 35 \u00edndices de referencia del Libor e incluir cl\u00e1usulas de respaldo que determinen los sustitutos del Libor. Y en eso est\u00e1n los afectados por hipotecas multidivisa, esperando a conocer en muchos casos cu\u00e1l ser\u00e1 el \u00edndice que sustituya al Libor.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En febrero de este a\u00f1o, la Uni\u00f3n Europea aprob\u00f3 el <a href=\"https:\/\/www.boe.es\/doue\/2021\/049\/L00006-00017.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Reglamento 2021\/168 de 10 de febrero de 2021<\/a> con el que pretende que con el que se establece que la Comisi\u00f3n Europea deb\u00eda crear un \u00edndice que sustituyese a esta tasa. Este organismo cre\u00f3 el \u201c\u20acSTR\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Uno de los mayores peligros para el hipotecado de la sustituci\u00f3n del Libor por el \u201c\u20acSTR\u201d es el desconocimiento de este \u00edndice, debido principalmente a la poca informaci\u00f3n de la que dispone y el conocimiento financiero con el que pueda contar el hipotecado.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En reclamador.es creemos que si las entidades financieras optan por la sustituci\u00f3n de uno por otro \u00edndice, <strong>el hipotecado estar\u00e1 en clara indefensi\u00f3n<\/strong>. En este caso, la mejor opci\u00f3n para el prestatario es sustituir el Libor por el Eur\u00edbor, \u00edndice mayoritario utilizado en Espa\u00f1a y que puede ser m\u00e1s conocido o disponer de m\u00e1s informaci\u00f3n por parte del hipotecado.<\/span><\/p>\n<h2><strong>\u00bfQuieres reclamar tu hipoteca multidivisa?<\/strong><\/h2>\n<p>Si eres uno de los miles afectados en Espa\u00f1a por hipoteca multidivisa, en reclamador.es podemos ayudarte. Rellena el formulario y adj\u00fantanos la documentaci\u00f3n con la que cuentes, nuestros abogados expertos en Derecho Bancario estudiar\u00e1n tu documentaci\u00f3n. Te enviaremos un informe donde te contamos si tu reclamaci\u00f3n de hipoteca multidivisa es viable y qu\u00e9 cantidad reclamar reclamar a tu entidad financiera.\u00a0<\/p>\n<h2 style=\"text-align: center;\"><a class=\"button-lead\" href=\"https:\/\/www.reclamador.es\/banco\/hipoteca-multidivisa\/formulario\/\" rel=\"nofollow noopener\"><strong>Inicia aqu\u00ed tu reclamaci\u00f3n de hipoteca multidivisa<\/strong><\/a><\/h2>\n<p>\u00a0<\/p>\n<div class=\"ttr_end\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Con el fin del a\u00f1o 2021 tambi\u00e9n llegar\u00e1 el adi\u00f3s al London InterBank Offered Rate -LIBOR- \u00edndice al que estaban referenciadas numerosas hipotecas en nuestro pa\u00eds, principalmente aquellas firmadas con el \u201cboom inmobiliario\u201d y el auge de las conocidas como \u201chipotecas multidivisa\u201d.\u00a0 Para los que no conozcan el Libor, podr\u00eda decirse que es como el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[393],"tags":[278,584],"class_list":{"0":"post-27716","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-consejos","8":"tag-banca","9":"tag-multidivisa","10":"entry"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fin al Libor de las hipotecas el 31 de diciembre de 2021<\/title>\n<meta name=\"description\" content=\"Con el fin del a\u00f1o 2021, tambi\u00e9n desaparecer\u00e1 el Libor de las hipotecas. Pero los bancos no han informado qu\u00e9 pasar\u00e1 con las hipotecas Libor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fin al Libor de las hipotecas el 31 de diciembre de 2021\" \/>\n<meta property=\"og:description\" content=\"Con el fin del a\u00f1o 2021, tambi\u00e9n desaparecer\u00e1 el Libor de las hipotecas. Pero los bancos no han informado qu\u00e9 pasar\u00e1 con las hipotecas Libor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/\" \/>\n<meta property=\"og:site_name\" content=\"Rebeldes con causa, el blog de reclamador.es\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/reclamador.es\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T08:17:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-29T10:48:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo reclamador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@reclamador\" \/>\n<meta name=\"twitter:site\" content=\"@reclamador\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo reclamador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/\"},\"author\":{\"name\":\"Equipo reclamador\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#\\\/schema\\\/person\\\/1ed83eef8b6566cb5e4c812d9bc5c4bf\"},\"headline\":\"Fin al Libor en las hipotecas\",\"datePublished\":\"2021-10-14T08:17:18+00:00\",\"dateModified\":\"2024-05-29T10:48:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/fin-del-libor-diciembre-2021.jpg?fit=1200%2C674&ssl=1\",\"keywords\":[\"banca\",\"multidivisa\"],\"articleSection\":[\"Consejos legales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/\",\"url\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/\",\"name\":\"Fin al Libor de las hipotecas el 31 de diciembre de 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/fin-del-libor-diciembre-2021.jpg?fit=1200%2C674&ssl=1\",\"datePublished\":\"2021-10-14T08:17:18+00:00\",\"dateModified\":\"2024-05-29T10:48:26+00:00\",\"description\":\"Con el fin del a\u00f1o 2021, tambi\u00e9n desaparecer\u00e1 el Libor de las hipotecas. Pero los bancos no han informado qu\u00e9 pasar\u00e1 con las hipotecas Libor.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/fin-del-libor-diciembre-2021.jpg?fit=1200%2C674&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/fin-del-libor-diciembre-2021.jpg?fit=1200%2C674&ssl=1\",\"width\":1200,\"height\":674,\"caption\":\"\u00bfQu\u00e9 pasar\u00e1 el 1 de enero de 2022 con las hipotecas Libor?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/fin-al-libor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fin al Libor en las hipotecas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/\",\"name\":\"Rebeldes con causa, el blog de reclamador.es\",\"description\":\"Noticias, entrevistas y consejos sobre reclamaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#organization\",\"name\":\"reclamador.es\",\"url\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-reclamador.png?fit=1200%2C144&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-reclamador.png?fit=1200%2C144&ssl=1\",\"width\":1200,\"height\":144,\"caption\":\"reclamador.es\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/reclamador.es\",\"https:\\\/\\\/x.com\\\/reclamador\",\"https:\\\/\\\/www.instagram.com\\\/reclamador.es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/reclamador-es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Reclamadores\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#\\\/schema\\\/person\\\/1ed83eef8b6566cb5e4c812d9bc5c4bf\",\"name\":\"Equipo reclamador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6442ecdc2c4472c600c113f34d340feca47107d6aa4f42f1e3e75a2a8e28a760?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6442ecdc2c4472c600c113f34d340feca47107d6aa4f42f1e3e75a2a8e28a760?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6442ecdc2c4472c600c113f34d340feca47107d6aa4f42f1e3e75a2a8e28a760?s=96&d=mm&r=g\",\"caption\":\"Equipo reclamador\"},\"description\":\"Las personas que hacen posible reclamador.es\",\"url\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/author\\\/administrador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fin al Libor de las hipotecas el 31 de diciembre de 2021","description":"Con el fin del a\u00f1o 2021, tambi\u00e9n desaparecer\u00e1 el Libor de las hipotecas. Pero los bancos no han informado qu\u00e9 pasar\u00e1 con las hipotecas Libor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/","og_locale":"es_ES","og_type":"article","og_title":"Fin al Libor de las hipotecas el 31 de diciembre de 2021","og_description":"Con el fin del a\u00f1o 2021, tambi\u00e9n desaparecer\u00e1 el Libor de las hipotecas. Pero los bancos no han informado qu\u00e9 pasar\u00e1 con las hipotecas Libor.","og_url":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/","og_site_name":"Rebeldes con causa, el blog de reclamador.es","article_publisher":"https:\/\/www.facebook.com\/reclamador.es","article_published_time":"2021-10-14T08:17:18+00:00","article_modified_time":"2024-05-29T10:48:26+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg","type":"image\/jpeg"}],"author":"Equipo reclamador","twitter_card":"summary_large_image","twitter_creator":"@reclamador","twitter_site":"@reclamador","twitter_misc":{"Escrito por":"Equipo reclamador","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/#article","isPartOf":{"@id":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/"},"author":{"name":"Equipo reclamador","@id":"https:\/\/www.reclamador.es\/blog\/#\/schema\/person\/1ed83eef8b6566cb5e4c812d9bc5c4bf"},"headline":"Fin al Libor en las hipotecas","datePublished":"2021-10-14T08:17:18+00:00","dateModified":"2024-05-29T10:48:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/www.reclamador.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg?fit=1200%2C674&ssl=1","keywords":["banca","multidivisa"],"articleSection":["Consejos legales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.reclamador.es\/blog\/fin-al-libor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/","url":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/","name":"Fin al Libor de las hipotecas el 31 de diciembre de 2021","isPartOf":{"@id":"https:\/\/www.reclamador.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/#primaryimage"},"image":{"@id":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg?fit=1200%2C674&ssl=1","datePublished":"2021-10-14T08:17:18+00:00","dateModified":"2024-05-29T10:48:26+00:00","description":"Con el fin del a\u00f1o 2021, tambi\u00e9n desaparecer\u00e1 el Libor de las hipotecas. Pero los bancos no han informado qu\u00e9 pasar\u00e1 con las hipotecas Libor.","breadcrumb":{"@id":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reclamador.es\/blog\/fin-al-libor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/#primaryimage","url":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg?fit=1200%2C674&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg?fit=1200%2C674&ssl=1","width":1200,"height":674,"caption":"\u00bfQu\u00e9 pasar\u00e1 el 1 de enero de 2022 con las hipotecas Libor?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.reclamador.es\/blog\/fin-al-libor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.reclamador.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Fin al Libor en las hipotecas"}]},{"@type":"WebSite","@id":"https:\/\/www.reclamador.es\/blog\/#website","url":"https:\/\/www.reclamador.es\/blog\/","name":"Rebeldes con causa, el blog de reclamador.es","description":"Noticias, entrevistas y consejos sobre reclamaciones","publisher":{"@id":"https:\/\/www.reclamador.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reclamador.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.reclamador.es\/blog\/#organization","name":"reclamador.es","url":"https:\/\/www.reclamador.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.reclamador.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2020\/01\/logo-reclamador.png?fit=1200%2C144&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2020\/01\/logo-reclamador.png?fit=1200%2C144&ssl=1","width":1200,"height":144,"caption":"reclamador.es"},"image":{"@id":"https:\/\/www.reclamador.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/reclamador.es","https:\/\/x.com\/reclamador","https:\/\/www.instagram.com\/reclamador.es\/","https:\/\/www.linkedin.com\/company\/reclamador-es","https:\/\/www.youtube.com\/user\/Reclamadores"]},{"@type":"Person","@id":"https:\/\/www.reclamador.es\/blog\/#\/schema\/person\/1ed83eef8b6566cb5e4c812d9bc5c4bf","name":"Equipo reclamador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6442ecdc2c4472c600c113f34d340feca47107d6aa4f42f1e3e75a2a8e28a760?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6442ecdc2c4472c600c113f34d340feca47107d6aa4f42f1e3e75a2a8e28a760?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6442ecdc2c4472c600c113f34d340feca47107d6aa4f42f1e3e75a2a8e28a760?s=96&d=mm&r=g","caption":"Equipo reclamador"},"description":"Las personas que hacen posible reclamador.es","url":"https:\/\/www.reclamador.es\/blog\/author\/administrador\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/10\/fin-del-libor-diciembre-2021.jpg?fit=1200%2C674&ssl=1","jetpack-related-posts":[{"id":5243,"url":"https:\/\/www.reclamador.es\/blog\/causas-las-reclamar-una-hipoteca-multidivisa\/","url_meta":{"origin":27716,"position":0},"title":"Causas por las que reclamar una hipoteca multidivisa","author":"Equipo reclamador","date":"24 noviembre, 2020","format":false,"excerpt":"Pagar el precio de una casa al contado se hac\u00eda, y se hace, pr\u00e1cticamente imposible para la mayor parte de la poblaci\u00f3n en Espa\u00f1a. Por ello, muchos consumidores recurren a un pr\u00e9stamo en modo de hipoteca para obtener un hogar en propiedad. Pero a la hora de elegir una hipoteca\u2026","rel":"","context":"En \u00abConsejos legales\u00bb","block_context":{"text":"Consejos legales","link":"https:\/\/www.reclamador.es\/blog\/consejos\/"},"img":{"alt_text":"Hipoteca multidivisa: puedes solicitar la nulidad\u00a0bas\u00e1ndote en el d\u00e9ficit de informaci\u00f3n padecido","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2020\/11\/apartamento-vivienda.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2020\/11\/apartamento-vivienda.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2020\/11\/apartamento-vivienda.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2020\/11\/apartamento-vivienda.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2020\/11\/apartamento-vivienda.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15658,"url":"https:\/\/www.reclamador.es\/blog\/sentencia-europea-hipoteca-multidivisa\/","url_meta":{"origin":27716,"position":1},"title":"An\u00e1lisis de la sentencia del TJUE sobre hipoteca multidivisa: Europa marca el camino a los juzgados espa\u00f1oles","author":"Equipo reclamador","date":"21 septiembre, 2017","format":false,"excerpt":"Otro varapalo m\u00e1s para la banca espa\u00f1ola. En esta ocasi\u00f3n viene por parte del Tribunal de Justicia de la Uni\u00f3n Europea (TJUE). Este Tribunal ha dictado la primera sentencia en relaci\u00f3n a las condiciones que han de concurrir en un pr\u00e9stamo hipotecario multidivisa para que sea considerado abusivo. De nuevo,\u2026","rel":"","context":"En \u00abNoticias y actualidad\u00bb","block_context":{"text":"Noticias y actualidad","link":"https:\/\/www.reclamador.es\/blog\/noticias\/"},"img":{"alt_text":"Hipoteca multidivisa TJUE","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/09\/hipoteca-multidivisa-tjue-analisis-reclamador.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/09\/hipoteca-multidivisa-tjue-analisis-reclamador.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/09\/hipoteca-multidivisa-tjue-analisis-reclamador.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/09\/hipoteca-multidivisa-tjue-analisis-reclamador.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/09\/hipoteca-multidivisa-tjue-analisis-reclamador.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":20930,"url":"https:\/\/www.reclamador.es\/blog\/bancos-mas-reclamados-2018\/","url_meta":{"origin":27716,"position":2},"title":"\u00bfCu\u00e1l ha sido el banco m\u00e1s reclamado en 2018?","author":"Equipo reclamador","date":"30 enero, 2019","format":false,"excerpt":"Con enero llega el momento de analizar los datos del a\u00f1o anterior y, por ello, en reclamador.es hemos analizado cu\u00e1les han sido los bancos m\u00e1s reclamados por nuestros clientes durante 2018. En total, casi 6.000 reclamaciones por gastos de formalizaci\u00f3n de hipoteca, cl\u00e1usula suelo e hipoteca multidivisa. Del an\u00e1lisis se\u2026","rel":"","context":"En \u00abNoticias y actualidad\u00bb","block_context":{"text":"Noticias y actualidad","link":"https:\/\/www.reclamador.es\/blog\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2019\/01\/ranking-bancos-mas-reclamados.jpg?fit=1200%2C799&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2019\/01\/ranking-bancos-mas-reclamados.jpg?fit=1200%2C799&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2019\/01\/ranking-bancos-mas-reclamados.jpg?fit=1200%2C799&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2019\/01\/ranking-bancos-mas-reclamados.jpg?fit=1200%2C799&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2019\/01\/ranking-bancos-mas-reclamados.jpg?fit=1200%2C799&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3399,"url":"https:\/\/www.reclamador.es\/blog\/hipoteca-multidivisa-sentencia-tribunal-supremo\/","url_meta":{"origin":27716,"position":3},"title":"Hipoteca multidivisa: primera sentencia del Tribunal Supremo","author":"Equipo reclamador","date":"30 septiembre, 2015","format":false,"excerpt":"El pasado 20 de mayo de 2015 se reuni\u00f3 el Pleno de la Sala Civil del Tribunal Supremo con el fin de resolver el recurso extraordinario por infracci\u00f3n procesal y recurso de casaci\u00f3n en un procedimiento que se\u00a0 inici\u00f3 con la intenci\u00f3n de que se declarar\u00e1 la nulidad de la\u2026","rel":"","context":"En \u00abNoticias y actualidad\u00bb","block_context":{"text":"Noticias y actualidad","link":"https:\/\/www.reclamador.es\/blog\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2015\/09\/IMG_0823.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2015\/09\/IMG_0823.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2015\/09\/IMG_0823.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2015\/09\/IMG_0823.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2015\/09\/IMG_0823.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":16205,"url":"https:\/\/www.reclamador.es\/blog\/sentencia-supremo-hipoteca-multidivisa\/","url_meta":{"origin":27716,"position":4},"title":"El Supremo anula las hipotecas multidivisas que no sean transparentes","author":"Equipo reclamador","date":"16 noviembre, 2017","format":false,"excerpt":"Entre 50.000 y 60.000 afectados por hipotecas multidivisas han visto c\u00f3mo se allanaba su camino para recuperar todo lo que han pagado de m\u00e1s. Y es que se public\u00f3 una sentencia del Tribunal Supremo en la que se daba la raz\u00f3n a un consumidor. El demandante pidi\u00f3 en 2008 un\u2026","rel":"","context":"En \u00abNoticias y actualidad\u00bb","block_context":{"text":"Noticias y actualidad","link":"https:\/\/www.reclamador.es\/blog\/noticias\/"},"img":{"alt_text":"reclamaciones de hipotecas multidivisas sentencia Supremo","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/11\/sentencia-supremo-hipoteca-multidivisa.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/11\/sentencia-supremo-hipoteca-multidivisa.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/11\/sentencia-supremo-hipoteca-multidivisa.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/11\/sentencia-supremo-hipoteca-multidivisa.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/11\/sentencia-supremo-hipoteca-multidivisa.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8843,"url":"https:\/\/www.reclamador.es\/blog\/ivan-bayarri-entrevista-multidivisa\/","url_meta":{"origin":27716,"position":5},"title":"Iv\u00e1n Bayarri, afectado multidivisa: \u201cLa imagen de abogados con despachos caros y trajes de tirantes me sobra\u201d","author":"Cristina Naveda","date":"5 julio, 2017","format":false,"excerpt":"Esta semana conocemos a Iv\u00e1n Bayarri (Madrid, 49 a\u00f1os), un \"s\u00faper reclamador\" que ha confiado en nosotros tres reclamaciones: la anulaci\u00f3n de su hipoteca multidivisa con Bankinter que a\u00fan est\u00e1 en proceso, los gastos de formalizaci\u00f3n de su hipoteca, y la cancelaci\u00f3n del vuelo de su hijo menor de edad,\u2026","rel":"","context":"En \u00abConoce todo lo que sucede en reclamador.es\u00bb","block_context":{"text":"Conoce todo lo que sucede en reclamador.es","link":"https:\/\/www.reclamador.es\/blog\/reclamadores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/07\/IMG_1802.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/07\/IMG_1802.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/07\/IMG_1802.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/07\/IMG_1802.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2017\/07\/IMG_1802.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/posts\/27716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/comments?post=27716"}],"version-history":[{"count":2,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/posts\/27716\/revisions"}],"predecessor-version":[{"id":32389,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/posts\/27716\/revisions\/32389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/media\/27718"}],"wp:attachment":[{"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/media?parent=27716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/categories?post=27716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/tags?post=27716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}