{"id":26416,"date":"2021-01-21T10:30:07","date_gmt":"2021-01-21T09:30:07","guid":{"rendered":"https:\/\/www.reclamador.es\/blog\/?p=26416"},"modified":"2023-06-23T09:49:25","modified_gmt":"2023-06-23T07:49:25","slug":"iberia-compra-air-europa-que-pasa-con-reclamaciones","status":"publish","type":"post","link":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/","title":{"rendered":"Si Iberia adquiere Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones de los viajeros?"},"content":{"rendered":"<div class=\"ttr_start\"><\/div>\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;26416&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;3&quot;,&quot;greet&quot;:&quot;Valora este art\u00edculo&quot;,&quot;legend&quot;:&quot;5\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;20&quot;,&quot;title&quot;:&quot;Si Iberia adquiere Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones de los viajeros?&quot;,&quot;width&quot;:&quot;113.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 113.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 3px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 20px; height: 20px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 16px;\">\n            5\/5 - (1 voto)    <\/div>\n    <\/div>\n\n<figure id=\"attachment_26421\" aria-describedby=\"caption-attachment-26421\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26421\" src=\"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?resize=1200%2C800&#038;ssl=1\" alt=\"iberia compra air europa\" width=\"1200\" height=\"800\" srcset=\"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-26421\" class=\"wp-caption-text\"><em>An\u00e1lisis: Iberia compra Air Europa<\/em><\/figcaption><\/figure>\n<p dir=\"ltr\"><a href=\"https:\/\/www.reclamador.es\/aerolineas\/iberia\/\">Iberia<\/a> est\u00e1 un paso m\u00e1s cerca de la definitiva compra de <a href=\"https:\/\/www.reclamador.es\/aerolineas\/air-europa\/\">Air Europa<\/a>. La aerol\u00ednea del Grupo IAG ha cerrado la compra de la compa\u00f1\u00eda a\u00e9rea perteneciente a Globalia por 500 millones de euros y se cree que la operaci\u00f3n podr\u00eda estar concluida en el segundo semestre de este a\u00f1o.\u00a0<\/p>\n<p dir=\"ltr\">Conocida esta noticia, en reclamador.es vamos a analizar las principales consecuencias de esta operaci\u00f3n para los clientes de Iberia y Air Europa.\u00a0<\/p>\n<h2 dir=\"ltr\"><strong>\u00bfQu\u00e9 pasa con las reclamaciones ya en curso?<\/strong><\/h2>\n<p dir=\"ltr\">En cuanto a las reclamaciones ya iniciadas por los viajeros frente a estas aerol\u00edneas, nada cambia. Desde reclamador.es queremos lanzar un mensaje de tranquilidad para los miles de viajeros que tienen ya iniciadas frente a Air Europa, pues no deber\u00e1n iniciar una nueva acci\u00f3n frente a la aerol\u00ednea.<\/p>\n<h2 dir=\"ltr\"><strong>Iberia compra Air Europa<\/strong><\/h2>\n<p dir=\"ltr\">Seg\u00fan se conozcan m\u00e1s detalles de esta operaci\u00f3n entre los dos gigantes del transporte a\u00e9reo, habr\u00e1 que analizar la f\u00f3rmula jur\u00eddica con la que se lleva a cabo esta compra, si bien todo hace indicar que Air Europa seguir\u00e1 operando con su marca, al igual que Iberia, y la compa\u00f1\u00eda hasta ahora de Globalia, se integrar\u00e1 junto a British Airways, Vueling o Iberia en el Grupo IAG.\u00a0<\/p>\n<h2 dir=\"ltr\"><strong>reclamador.es pide que la compra de Air Europa por Iberia no perjudique a los viajeros<\/strong><\/h2>\n<p dir=\"ltr\">Desde reclamador.es esperamos que esta operaci\u00f3n no conlleve ning\u00fan perjuicio para los clientes de estas aerol\u00edneas, tanto para los que ya tienen iniciadas acciones contra ellas como para sus futuros viajeros, pues no debemos olvidar que ambas compa\u00f1\u00edas a\u00e9reas han venido siendo a\u00f1o tras a\u00f1o de las m\u00e1s reclamadas por <a href=\"https:\/\/www.reclamador.es\/aerolineas\/cancelacion-vuelo\/\">cancelaciones<\/a>, <a href=\"https:\/\/www.reclamador.es\/aerolineas\/retraso-vuelo\/\">retrasos de vuelos<\/a>, e incluso por <a href=\"https:\/\/www.reclamador.es\/aerolineas\/overbooking\/\">overbooking<\/a> o <a href=\"https:\/\/www.reclamador.es\/aerolineas\/problemas-equipaje\/\">p\u00e9rdida de equipaje<\/a>, en nuestro pa\u00eds y esperamos que no utilicen ahora su nueva posici\u00f3n para disminuir los derechos de sus clientes recogidos en el Reglamento Europeo 261\/2004\u201d.\u00a0<\/p>\n<p dir=\"ltr\">Por \u00faltimo, en reclamador.es solicitamos a ambas compa\u00f1\u00edas que no aprovechen su posici\u00f3n en el mercado espa\u00f1ol para incrementar los precios de los billetes, especialmente en el largo radio.<\/p>\n<h2 style=\"text-align: center;\"><strong><a class=\"button-lead\" href=\"https:\/\/www.reclamador.es\/aerolineas\/\">\u00bfQuieres hacer una reclamaci\u00f3n de vuelo?<\/a><\/strong><\/h2>\n<p>Si te ha parecido interesante esta noticia sobre la compra de Air Europa por Iberia, comp\u00e1rtelo en tus redes sociales.\u00a0<\/p>\n<div>\u00a0<\/div>\n<div class=\"ttr_end\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Iberia est\u00e1 un paso m\u00e1s cerca de la definitiva compra de Air Europa. La aerol\u00ednea del Grupo IAG ha cerrado la compra de la compa\u00f1\u00eda a\u00e9rea perteneciente a Globalia por 500 millones de euros y se cree que la operaci\u00f3n podr\u00eda estar concluida en el segundo semestre de este a\u00f1o.\u00a0 Conocida esta noticia, en reclamador.es [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":26421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[392],"tags":[380],"class_list":{"0":"post-26416","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias","8":"tag-aerolineas","9":"entry"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Iberia compra Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones?<\/title>\n<meta name=\"description\" content=\"Iberia compra Air Europa. En reclamador.es explicamos qu\u00e9 pasa con las reclamaciones ya iniciadas frente a Air Europa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iberia compra Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones?\" \/>\n<meta property=\"og:description\" content=\"Iberia compra Air Europa. En reclamador.es explicamos qu\u00e9 pasa con las reclamaciones ya iniciadas frente a Air Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Rebeldes con causa, el blog de reclamador.es\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/reclamador.es\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-21T09:30:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-23T07:49:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juliana Siqueira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@reclamador\" \/>\n<meta name=\"twitter:site\" content=\"@reclamador\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juliana Siqueira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/\"},\"author\":{\"name\":\"Juliana Siqueira\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#\\\/schema\\\/person\\\/d7ae0789516cf0f92c022fffa907b0d4\"},\"headline\":\"Si Iberia adquiere Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones de los viajeros?\",\"datePublished\":\"2021-01-21T09:30:07+00:00\",\"dateModified\":\"2023-06-23T07:49:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/\"},\"wordCount\":420,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1\",\"keywords\":[\"aerol\u00edneas\"],\"articleSection\":[\"Noticias y actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/\",\"url\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/\",\"name\":\"Iberia compra Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2021-01-21T09:30:07+00:00\",\"dateModified\":\"2023-06-23T07:49:25+00:00\",\"description\":\"Iberia compra Air Europa. En reclamador.es explicamos qu\u00e9 pasa con las reclamaciones ya iniciadas frente a Air Europa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800,\"caption\":\"An\u00e1lisis: Iberia compra Air Europa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/iberia-compra-air-europa-que-pasa-con-reclamaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Si Iberia adquiere Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones de los viajeros?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/\",\"name\":\"Rebeldes con causa, el blog de reclamador.es\",\"description\":\"Noticias, entrevistas y consejos sobre reclamaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#organization\",\"name\":\"reclamador.es\",\"url\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-reclamador.png?fit=1200%2C144&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.reclamador.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-reclamador.png?fit=1200%2C144&ssl=1\",\"width\":1200,\"height\":144,\"caption\":\"reclamador.es\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/reclamador.es\",\"https:\\\/\\\/x.com\\\/reclamador\",\"https:\\\/\\\/www.instagram.com\\\/reclamador.es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/reclamador-es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Reclamadores\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/#\\\/schema\\\/person\\\/d7ae0789516cf0f92c022fffa907b0d4\",\"name\":\"Juliana Siqueira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b9b37bcc38c281d801e30fd31309ddfc07be57296accee4fa5cad0c54d15359?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b9b37bcc38c281d801e30fd31309ddfc07be57296accee4fa5cad0c54d15359?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b9b37bcc38c281d801e30fd31309ddfc07be57296accee4fa5cad0c54d15359?s=96&d=mm&r=g\",\"caption\":\"Juliana Siqueira\"},\"description\":\"Responsable Legal de Aerol\u00edneas. Creo que las mejores soluciones son las que se alcanzan de forma amistosa y lo intento aplicar a cada procedimiento que se tramita en reclamador.es.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/juliana-siqueira-159b09107\\\/\"],\"url\":\"https:\\\/\\\/www.reclamador.es\\\/blog\\\/author\\\/juliana-siqueira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iberia compra Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones?","description":"Iberia compra Air Europa. En reclamador.es explicamos qu\u00e9 pasa con las reclamaciones ya iniciadas frente a Air Europa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/","og_locale":"es_ES","og_type":"article","og_title":"Iberia compra Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones?","og_description":"Iberia compra Air Europa. En reclamador.es explicamos qu\u00e9 pasa con las reclamaciones ya iniciadas frente a Air Europa.","og_url":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/","og_site_name":"Rebeldes con causa, el blog de reclamador.es","article_publisher":"https:\/\/www.facebook.com\/reclamador.es","article_published_time":"2021-01-21T09:30:07+00:00","article_modified_time":"2023-06-23T07:49:25+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Juliana Siqueira","twitter_card":"summary_large_image","twitter_creator":"@reclamador","twitter_site":"@reclamador","twitter_misc":{"Escrito por":"Juliana Siqueira","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/#article","isPartOf":{"@id":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/"},"author":{"name":"Juliana Siqueira","@id":"https:\/\/www.reclamador.es\/blog\/#\/schema\/person\/d7ae0789516cf0f92c022fffa907b0d4"},"headline":"Si Iberia adquiere Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones de los viajeros?","datePublished":"2021-01-21T09:30:07+00:00","dateModified":"2023-06-23T07:49:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/"},"wordCount":420,"commentCount":0,"publisher":{"@id":"https:\/\/www.reclamador.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1","keywords":["aerol\u00edneas"],"articleSection":["Noticias y actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/","url":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/","name":"Iberia compra Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones?","isPartOf":{"@id":"https:\/\/www.reclamador.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/#primaryimage"},"image":{"@id":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1","datePublished":"2021-01-21T09:30:07+00:00","dateModified":"2023-06-23T07:49:25+00:00","description":"Iberia compra Air Europa. En reclamador.es explicamos qu\u00e9 pasa con las reclamaciones ya iniciadas frente a Air Europa.","breadcrumb":{"@id":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/#primaryimage","url":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800,"caption":"An\u00e1lisis: Iberia compra Air Europa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.reclamador.es\/blog\/iberia-compra-air-europa-que-pasa-con-reclamaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.reclamador.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Si Iberia adquiere Air Europa: \u00bfqu\u00e9 pasa con las reclamaciones de los viajeros?"}]},{"@type":"WebSite","@id":"https:\/\/www.reclamador.es\/blog\/#website","url":"https:\/\/www.reclamador.es\/blog\/","name":"Rebeldes con causa, el blog de reclamador.es","description":"Noticias, entrevistas y consejos sobre reclamaciones","publisher":{"@id":"https:\/\/www.reclamador.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reclamador.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.reclamador.es\/blog\/#organization","name":"reclamador.es","url":"https:\/\/www.reclamador.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.reclamador.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2020\/01\/logo-reclamador.png?fit=1200%2C144&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2020\/01\/logo-reclamador.png?fit=1200%2C144&ssl=1","width":1200,"height":144,"caption":"reclamador.es"},"image":{"@id":"https:\/\/www.reclamador.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/reclamador.es","https:\/\/x.com\/reclamador","https:\/\/www.instagram.com\/reclamador.es\/","https:\/\/www.linkedin.com\/company\/reclamador-es","https:\/\/www.youtube.com\/user\/Reclamadores"]},{"@type":"Person","@id":"https:\/\/www.reclamador.es\/blog\/#\/schema\/person\/d7ae0789516cf0f92c022fffa907b0d4","name":"Juliana Siqueira","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9b9b37bcc38c281d801e30fd31309ddfc07be57296accee4fa5cad0c54d15359?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9b9b37bcc38c281d801e30fd31309ddfc07be57296accee4fa5cad0c54d15359?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9b9b37bcc38c281d801e30fd31309ddfc07be57296accee4fa5cad0c54d15359?s=96&d=mm&r=g","caption":"Juliana Siqueira"},"description":"Responsable Legal de Aerol\u00edneas. Creo que las mejores soluciones son las que se alcanzan de forma amistosa y lo intento aplicar a cada procedimiento que se tramita en reclamador.es.","sameAs":["https:\/\/www.linkedin.com\/in\/juliana-siqueira-159b09107\/"],"url":"https:\/\/www.reclamador.es\/blog\/author\/juliana-siqueira\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2021\/01\/iberia-compra-air-europa.jpg?fit=1200%2C800&ssl=1","jetpack-related-posts":[{"id":35485,"url":"https:\/\/www.reclamador.es\/blog\/cancelaciones-de-trenes-en-malaga-sevilla-alternativa-vuelos-iberia-air-europa\/","url_meta":{"origin":26416,"position":0},"title":"Afectados por cancelaciones de trenes en M\u00e1laga y Sevilla: la alternativa de vuelos de Iberia y Air Europa","author":"Equipo reclamador","date":"20 enero, 2026","format":false,"excerpt":"Tras el tr\u00e1gico accidente de alta velocidad que se produjo el 18 de enero de este 2026 a la altura de la localidad de Adamuz, en C\u00f3rdoba, la l\u00ednea ferroviaria que conecta Madrid con Andaluc\u00eda est\u00e1 temporalmente cerrada, al menos, hasta el pr\u00f3ximo 2 de febrero, seg\u00fan fuentes oficiales. \u00bfQu\u00e9\u2026","rel":"","context":"En \u00abNoticias y actualidad\u00bb","block_context":{"text":"Noticias y actualidad","link":"https:\/\/www.reclamador.es\/blog\/noticias\/"},"img":{"alt_text":"trenes cancelados en malaga y sevilla - vuelos alternativos","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-8.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-8.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-8.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-8.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-8.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":31928,"url":"https:\/\/www.reclamador.es\/blog\/ranking-aerolineas-mas-reclamadas-2023\/","url_meta":{"origin":26416,"position":1},"title":"Ranking aerol\u00edneas m\u00e1s reclamadas en 2023: Vueling a la cabeza","author":"Equipo reclamador","date":"30 enero, 2024","format":false,"excerpt":"Como cada a\u00f1o, en reclamador.es hemos preparado el ranking de las aerol\u00edneas m\u00e1s reclamadas por los viajeros, para conocer cu\u00e1les son las compa\u00f1\u00edas a\u00e9reas que m\u00e1s incidencias sufren cada a\u00f1o. Seg\u00fan nuestros datos, m\u00e1s de 39.000 personas han reclamado a 184 compa\u00f1\u00edas a\u00e9reas a lo largo de 2023. Las reclamaciones\u2026","rel":"","context":"En \u00abNoticias y actualidad\u00bb","block_context":{"text":"Noticias y actualidad","link":"https:\/\/www.reclamador.es\/blog\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2024\/01\/plane-2605014_1280.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2024\/01\/plane-2605014_1280.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2024\/01\/plane-2605014_1280.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2024\/01\/plane-2605014_1280.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2024\/01\/plane-2605014_1280.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":16846,"url":"https:\/\/www.reclamador.es\/blog\/aerolineas-mas-reclamadas-2017\/","url_meta":{"origin":26416,"position":2},"title":"Viajero, toma nota: las aerol\u00edneas m\u00e1s reclamadas en 2017","author":"Equipo reclamador","date":"25 enero, 2018","format":false,"excerpt":"Nos gusta viajar. Aprovechar un par de d\u00edas libres para coger un avi\u00f3n y desconectar. Conocer rincones de Espa\u00f1a y del resto del mundo. Prueba de ello es que por los aeropuertos espa\u00f1oles pasaron el a\u00f1o pasado 249,2 millones de viajeros. Sobrepasando as\u00ed en un 8,2% el tr\u00e1fico de pasajeros\u2026","rel":"","context":"En \u00abNoticias y actualidad\u00bb","block_context":{"text":"Noticias y actualidad","link":"https:\/\/www.reclamador.es\/blog\/noticias\/"},"img":{"alt_text":"aerolineas problem\u00e1ticas 2017","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2018\/01\/Ranking_aerolineas2017.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2018\/01\/Ranking_aerolineas2017.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2018\/01\/Ranking_aerolineas2017.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2018\/01\/Ranking_aerolineas2017.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2018\/01\/Ranking_aerolineas2017.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":32504,"url":"https:\/\/www.reclamador.es\/blog\/que-aerolineas-hacen-overbooking\/","url_meta":{"origin":26416,"position":3},"title":"\u00bfQu\u00e9 aerol\u00edneas hacen overbooking?","author":"Equipo reclamador","date":"18 junio, 2024","format":false,"excerpt":"El overbooking, o sobreventa de billetes, es una pr\u00e1ctica com\u00fan en la industria a\u00e9rea que puede causar muchos inconvenientes a los pasajeros. En reclamador.es hemos recopilado datos de las reclamaciones que hemos gestionado por overbooking a cada aerol\u00ednea, para ofrecerte una visi\u00f3n clara de las compa\u00f1\u00edas a\u00e9reas que m\u00e1s practican\u2026","rel":"","context":"En \u00abNoticias y actualidad\u00bb","block_context":{"text":"Noticias y actualidad","link":"https:\/\/www.reclamador.es\/blog\/noticias\/"},"img":{"alt_text":"ranking reclamaciones aerol\u00edneas overbooking reclamador","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2024\/06\/que-aerolineas-hacen-overbooking-1200x630-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2024\/06\/que-aerolineas-hacen-overbooking-1200x630-1.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2024\/06\/que-aerolineas-hacen-overbooking-1200x630-1.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2024\/06\/que-aerolineas-hacen-overbooking-1200x630-1.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2024\/06\/que-aerolineas-hacen-overbooking-1200x630-1.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":31325,"url":"https:\/\/www.reclamador.es\/blog\/ranking-verano-2023\/","url_meta":{"origin":26416,"position":4},"title":"Ranking verano 2023: Ryanair y Vueling, las aerol\u00edneas m\u00e1s reclamadas","author":"Equipo reclamador","date":"14 septiembre, 2023","format":false,"excerpt":"El verano siempre impacta con fuerza en el sector a\u00e9reo. No en vano, m\u00e1s de 12.000 personas han reclamado contra las aerol\u00edneas en los meses centrales de este verano con reclamador.es. Dado este importante volumen, hemos elaborado un ranking con las aerol\u00edneas m\u00e1s reclamadas entre junio, julio y agosto, para\u2026","rel":"","context":"En \u00abNoticias y actualidad\u00bb","block_context":{"text":"Noticias y actualidad","link":"https:\/\/www.reclamador.es\/blog\/noticias\/"},"img":{"alt_text":"reclamador.es reclamaciones a aerol\u00edneas ranking","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2023\/09\/Ranking-aerolineas-mas-reclamadas-verano-2023.jpg?fit=1200%2C639&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2023\/09\/Ranking-aerolineas-mas-reclamadas-verano-2023.jpg?fit=1200%2C639&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2023\/09\/Ranking-aerolineas-mas-reclamadas-verano-2023.jpg?fit=1200%2C639&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2023\/09\/Ranking-aerolineas-mas-reclamadas-verano-2023.jpg?fit=1200%2C639&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2023\/09\/Ranking-aerolineas-mas-reclamadas-verano-2023.jpg?fit=1200%2C639&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35469,"url":"https:\/\/www.reclamador.es\/blog\/fast-track-aeropuertos-aerolineas\/","url_meta":{"origin":26416,"position":5},"title":"Fast track en aeropuertos: \u00bfqu\u00e9 es y qu\u00e9 aerol\u00edneas lo ofrecen?","author":"Equipo reclamador","date":"15 enero, 2026","format":false,"excerpt":"Las colas en aeropuertos pueden suponer un gran estr\u00e9s para numerosas personas. Sentir que pierden el avi\u00f3n por las interminables filas en los controles de seguridad de los aeropuertos puede tener varias soluciones. La primera de ellas, llegar con la suficiente antelaci\u00f3n al aeropuerto. Y otra el fast track. A\u2026","rel":"","context":"En \u00abConsejos legales\u00bb","block_context":{"text":"Consejos legales","link":"https:\/\/www.reclamador.es\/blog\/consejos\/"},"img":{"alt_text":"Fast track y fast line aerolineas","src":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-7.jpg?fit=1200%2C630&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-7.jpg?fit=1200%2C630&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-7.jpg?fit=1200%2C630&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-7.jpg?fit=1200%2C630&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.reclamador.es\/blog\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-7.jpg?fit=1200%2C630&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/posts\/26416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/comments?post=26416"}],"version-history":[{"count":10,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/posts\/26416\/revisions"}],"predecessor-version":[{"id":31130,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/posts\/26416\/revisions\/31130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/media\/26421"}],"wp:attachment":[{"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/media?parent=26416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/categories?post=26416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reclamador.es\/blog\/wp-json\/wp\/v2\/tags?post=26416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}